{"id":78524,"date":"2026-05-21T17:22:11","date_gmt":"2026-05-21T14:22:11","guid":{"rendered":"https:\/\/kad-esh.org\/?p=78524"},"modified":"2026-05-21T20:42:58","modified_gmt":"2026-05-21T17:42:58","slug":"estas-esperando","status":"publish","type":"post","link":"https:\/\/kad-esh.org\/es\/estas-esperando\/","title":{"rendered":"\u00bfEst\u00e1s Esperando?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78425\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1.jpg\" alt=\"Are you waiting\" width=\"1491\" height=\"1055\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1.jpg 1491w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-770x545.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-1200x849.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-768x543.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-500x354.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-600x425.jpg 600w\" sizes=\"auto, (max-width: 1491px) 100vw, 1491px\" \/><br \/>\n<span class=\"torah-portion\">Porci\u00f3n de la Fiesta de SHAVUOT \u2013 Shemot (\u00c9xodo) 19:1-20:23. Haftar\u00e1: 1:1-28<\/span><\/p>\n<blockquote><p><i>Al ver el pueblo que Mois\u00e9s tardaba en bajar del monte, fueron a ver a Aar\u00f3n y le dijeron: \u00abAnda, haznos unos dioses que vayan delante de nosotros, porque a este Mois\u00e9s, que nos sac\u00f3 de Egipto, no sabemos qu\u00e9 pudo haberle sucedido.\u00bb<\/i> \u00c9xodo 32:1 (RVC)<\/p><\/blockquote>\n<h4 style=\"margin-top: 0;\"><strong>Shabat shalom amados.<\/strong><\/h4>\n<p>A veces se nos ha olvidado el h\u00e1bito de esperar el momento oportuno de Yah. Todo a nuestro alrededor es tan r\u00e1pido que nuestra capacidad de atenci\u00f3n se est\u00e1 acortando cada vez m\u00e1s. El problema es que, cuando nos impacientamos, podemos perder de vista por completo Su voluntad y caer en la idolatr\u00eda, pensando que le estamos sirviendo. Esto es lo que les sucedi\u00f3 a los antiguos israelitas: se impacientaron despu\u00e9s de 40 d\u00edas de esperar a que Mois\u00e9s bajara de la monta\u00f1a. \u00a1Creo que hoy en d\u00eda la gente no esperar\u00eda ni 40 minutos, y mucho menos 40 d\u00edas!<\/p>\n<p>La impaciencia por esperar el momento indicado por Yah llev\u00f3 a la gran mayor\u00eda de Israel a entregarse a la inmoralidad y la idolatr\u00eda. Se crearon un dios y se convencieron a s\u00ed mismos de que ese era el dios que los hab\u00eda liberado de la esclavitud.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78426\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2.jpg\" alt=\"Are you waiting\" width=\"1402\" height=\"1122\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2.jpg 1402w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2-770x616.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2-1200x960.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2-768x615.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2-500x400.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-2-600x480.jpg 600w\" sizes=\"auto, (max-width: 1402px) 100vw, 1402px\" \/><\/p>\n<p><i>Entonces todo el pueblo se quit\u00f3 los pendientes de oro que ten\u00edan en las orejas y los llevaron a Aar\u00f3n. \u00c9l los tom\u00f3 de sus manos y les dio forma con buril, e hizo de ellos un becerro de fundici\u00f3n. Y ellos dijeron: \u00abEste es tu dios, Israel, que te ha sacado de la tierra de Egipto\u00bb.<\/i> \u00c9xodo 32:3-4<\/p>\n<p>El resto de la historia no es nada agradable. YHVH vio el horrible libertinaje y envi\u00f3 a Mois\u00e9s. No para bendecir, sino para juzgar.<\/p>\n<p><i>Al d\u00eda siguiente se levantaron temprano y ofrecieron holocaustos y trajeron ofrendas de paz. El pueblo se sent\u00f3 a comer y a beber, y se levant\u00f3 a regocijarse. Entonces YHVH habl\u00f3 a Mois\u00e9s: \u00abDesciende pronto, porque tu pueblo, que sacaste de la tierra de Egipto, se ha corrompido.\u00bb<\/i> \u00c9xodo 32:6-7<\/p>\n<p>YHVH estaba a punto de destruir a toda la naci\u00f3n por este grave pecado, pero Mois\u00e9s intercedi\u00f3 por su pueblo.<\/p>\n<p><i>Ahora pues, d\u00e9jame, para que se encienda Mi ira contra ellos y los consuma. Pero de ti Yo har\u00e9 una gran naci\u00f3n\u00bb. Entonces Mois\u00e9s suplic\u00f3 ante YHVH su Elohim, y dijo: \u00abOh YHVH, \u00bfpor qu\u00e9 se enciende Tu ira contra Tu pueblo, que T\u00fa has sacado de la tierra de Egipto con gran poder y con mano fuerte?\u00bb<\/i> \u00c9xodo 32:10-11<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78427\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3.jpg\" alt=\"Are you waiting\" width=\"1491\" height=\"1055\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3.jpg 1491w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3-770x545.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3-1200x849.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3-768x543.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3-500x354.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-3-600x425.jpg 600w\" sizes=\"auto, (max-width: 1491px) 100vw, 1491px\" \/><\/p>\n<p>Cuando Mois\u00e9s descendi\u00f3, estaba furioso y rompi\u00f3 las tablas en las que estaban escritas las Diez Palabras con el dedo de Yah.<\/p>\n<p>\u201c<i>Tan pronto como Mois\u00e9s se acerc\u00f3 al campamento, vio el becerro y las danzas. Se encendi\u00f3 la ira de Mois\u00e9s, arroj\u00f3 las tablas de sus manos, y las hizo pedazos al pie del monte.\u201d<\/i> \u00c9xodo 32:19<\/p>\n<p>Ese d\u00eda se produjo una gran matanza y 3000 personas murieron a manos de sus propios hermanos.<\/p>\n<p>Y \u00e9l les dijo: \u00abAs\u00ed dice YHVH, Elohim de Israel: \u201cP\u00f3ngase cada uno la espada sobre el muslo, y pasen y repasen por el campamento de puerta en puerta, y maten cada uno a su hermano y a su amigo y a su vecino\u201d\u00bb. Los hijos de Lev\u00ed hicieron conforme a la palabra de Mois\u00e9s; y cayeron aquel d\u00eda unos 3,000 hombres del pueblo.\u201d \u00c9xodo 32:27-28<\/p>\n<p>\u00a1Vaya historia! Pero la causa principal de todo esto es la impaciencia. Quiz\u00e1s no hayas considerado este problema grave, pero lo es y causa un n\u00famero incalculable de problemas. Lo contrario a esto es esperar en YHVH. Espera hasta que \u00c9l te d\u00e9 luz verde; espera hasta que Sus promesas se cumplan. Espera a que llegue Su tiempo. Esperar no es postergar; es CONFIANZA.<\/p>\n<p>\u201c<i>Porque ustedes tienen necesidad de paciencia, para que cuando hayan hecho la voluntad de Elohim, obtengan la promesa. Porque dentro de muy poco tiempo, El que ha de venir vendr\u00e1 y no tardar\u00e1.\u201d<\/i> Hebreos 10:36-37<\/p>\n<p>No tomes el asunto en tus propias manos por impaciencia o frustraci\u00f3n. Mant\u00e9n el rumbo y permanece fiel a \u00c9l y a Su Llamado Divino, sin importar cu\u00e1nto tiempo tengas que esperar.<\/p>\n<p>\u201c<i>Mas Mi justo vivir\u00e1 por la emun\u00e1 (fe y confianza); y si retrocede, Mi alma no se complacer\u00e1 en \u00e9l.\u201d <\/i>Hebreos 10:38<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78428\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4.jpg\" alt=\"Are you waiting\" width=\"1456\" height=\"1080\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4.jpg 1456w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4-770x571.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4-1200x890.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4-768x570.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4-500x371.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-4-600x445.jpg 600w\" sizes=\"auto, (max-width: 1456px) 100vw, 1456px\" \/><\/p>\n<p>Espera con fe y confianza el cumplimiento de Su palabra y de Sus promesas. Y cuando llegue el momento, apres\u00farate a obedecer Sus mandamientos.<\/p>\n<p>\u201c<i>Pero los que esperan en YHVH renovar\u00e1n sus fuerzas. Se remontar\u00e1n con alas como las \u00e1guilas, correr\u00e1n y no se cansar\u00e1n, caminar\u00e1n y no se fatigar\u00e1n.\u201d<\/i> Isa\u00edas 40:31<\/p>\n<p>Hace 2000 a\u00f1os ocurri\u00f3 algo sin precedentes en Jerusal\u00e9n cuando Yeshua les dijo que esperaran.<\/p>\n<p>\u201c<i>Estando con ellos, les mand\u00f3 que no salieran de Jerusal\u00e9n hasta que, tal como ya les hab\u00eda dicho, recibieran la promesa del Padre. \u2015\u00abJuan los bautiz\u00f3 con agua\u00bb \u2014les record\u00f3\u2014, \u00abpero dentro de poco ustedes ser\u00e1n bautizados con el Esp\u00edritu Santo\u00bb.\u201d <\/i>Hechos 1:4-5 (NBV)<\/p>\n<p>El Ruaj Hakodesh (Esp\u00edritu Santo) descendi\u00f3 sobre todos aquellos que estaban obedeciendo la orden de esperar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78429\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5.jpg\" alt=\"Are you waiting\" width=\"862\" height=\"575\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5.jpg 862w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5-770x514.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5-768x512.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5-500x334.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-5-600x400.jpg 600w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/p>\n<p>\u00abSin embargo, cuando el Esp\u00edritu Santo descienda sobre ustedes recibir\u00e1n poder para ser mis testigos no s\u00f3lo en Jerusal\u00e9n, sino tambi\u00e9n en toda Judea, en Samaria y hasta lo \u00faltimo de la tierra.\u00bb Y mientras les dec\u00eda esto, ascendi\u00f3 al cielo y desapareci\u00f3 envuelto en una nube. Hechos 1:8-9 (NBV)<\/p>\n<p>Las \u00faltimas palabras de Yeshua fueron: \u201cEsperen con fe y recibir\u00e1n un poder extraordinario\u201d. Esperaron con fe y en oraci\u00f3n hasta la fiesta de Shavuot (Fiesta de las Semanas\/Pentecost\u00e9s), \u00a1y entonces sucedi\u00f3! Recibieron el cumplimiento de lo que Yeshua hab\u00eda prometido.<\/p>\n<p>\u201c<i>Cuando lleg\u00f3 el d\u00eda de Shavuot (Pentecost\u00e9s), estaban todos juntos en un mismo lugar, y de repente vino del cielo un ruido como el de una r\u00e1faga de viento impetuoso que llen\u00f3 toda la casa donde estaban sentados. Se les aparecieron lenguas como de fuego que, reparti\u00e9ndose, se posaron sobre cada uno de ellos. Todos fueron llenos del Esp\u00edritu Santo y comenzaron a hablar en otras lenguas, seg\u00fan el Esp\u00edritu les daba habilidad para expresarse.\u201d<\/i> Hechos 2:1-4<\/p>\n<p>\u00a1Esperar con fe, en oraci\u00f3n y obediencia, da resultados sin precedentes!<\/p>\n<p>\u00c9l promete bendiciones asombrosas a quienes le esperan.<\/p>\n<p>\u201c<i>Desde la antig\u00fcedad no hab\u00edan escuchado ni puesto atenci\u00f3n, ni el ojo hab\u00eda visto a un Elohim fuera de Ti que obrara a favor del que esperaba en \u00c9l.\u201d<\/i> Isa\u00edas 64:4<\/p>\n<p>\u00a1Jag Shavuot Sam\u00e9aj!<\/p>\n<p>Tus amigos y mentores israel\u00edes,<\/p>\n<p>Dra. Dominiquae y Rabino Baruch Bierman<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-75682\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/04\/ab-rabbi-coffeeshop.jpg\" alt=\"Archbishop Dominiquae and Rabbi Baruch Bierman\" width=\"375\" height=\"500\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-45445\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day.jpg\" alt=\"Revival of the Third Day\" width=\"300\" height=\"auto\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day.jpg 1000w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-194x300.jpg 194w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-663x1024.jpg 663w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-768x1187.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-994x1536.jpg 994w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-500x773.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-100x155.jpg 100w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-862x1332.jpg 862w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-600x927.jpg 600w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/03\/SPA-the-revival-of-the-third-day-64x99.jpg 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h4 style=\"margin-top: 0;\"><b>Adquiere el libro \u201cEl Avivamiento del Tercer D\u00eda\u201d <\/b><i>y comp\u00e1rtelo con otros<\/i><\/h4>\n<p><a class=\"button\" href=\"https:\/\/www.zionsgospel.com\/es\/tienda\/el-avivamiento-del-tercer-dia\/\" target=\"_blank\" rel=\"noopener\"><b>Ordena ahora<\/b><\/a><\/p>\n<h4 style=\"margin-top: 0;\"><b>Ver: \u00a1Shalom! Est\u00e9n Quietos<\/b><\/h4>\n<div class=\"x-resp-embed x-is-video x-is-youtube\"><iframe loading=\"lazy\" title=\"\u00a1Shalom! Est\u00e9n Quietos | Dra. Dominiquae Bierman | Israel\" width=\"742\" height=\"417\" src=\"https:\/\/www.youtube.com\/embed\/iXQiGBOnE4A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><a class=\"button\" href=\"https:\/\/youtu.be\/iXQiGBOnE4A\" target=\"_blank\" rel=\"noopener\"><strong>YouTube \u2192<\/strong><\/a><br \/>\n<a class=\"button\" href=\"https:\/\/rumble.com\/v79vf9w-shalom-estn-quietos-dra.-dominiquae-bierman-israel.html\" target=\"_blank\" rel=\"noopener\"><strong>Rumble \u2192 <\/strong><\/a><\/p>\n<ul class=\"display-posts-listing\"><li class=\"listing-item\"><a class=\"title\" href=\"https:\/\/kad-esh.org\/es\/shabbat-letter-ads\/\">Shabbat Letter ads<\/a><div class=\"content\"><p><strong>Hazte miembro de las Naciones Unidas por Israel<\/strong> y \u00fanete a nuestra conferencia mensual en l\u00ednea para miembros. \u00a1Recibir\u00e1s actualizaciones, instrucciones y ense\u00f1anzas prof\u00e9ticas en vivo cada mes, y ser\u00e1s parte de la Iglesia Ester apoyando a Israel!<\/p>\n<p><a class=\"button\" href=\"https:\/\/unitednationsforisrael.org\/es\/membresia\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00danete a UNIFY \u2192<\/strong><\/a><\/p>\n<h4><strong>Para enviar sus Diezmos y Ofrendas:<\/strong><\/h4>\n<ul>\n<li><strong>En l\u00ednea: <\/strong><a href=\"https:\/\/kad-esh.org\/es\/donaciones\/\">https:\/\/kad-esh.org\/es\/donaciones\/<\/a><\/li>\n<li><strong>Env\u00edenos un correo electr\u00f3nico <\/strong>a <a href=\"mailto:info@kad-esh.org\">info@kad-esh.org<\/a> para obtener los datos bancarios.<\/li>\n<li><strong>Por Zelle: <\/strong><a href=\"mailto:info@kad-esh.org\">info@kad-esh.org<\/a><\/li>\n<li><strong>Ll\u00e1menos <\/strong>en EE. UU. al 1-972-301-7087<\/li>\n<li><strong>Los cheques <\/strong>en d\u00f3lares estadounidenses, d\u00f3lares canadienses o libras esterlinas deben enviarse a Kad-Esh MAP Ministries, 52 Tuscan Way Ste 202-412, St Augustine, Florida 32092, EE. UU.<\/li>\n<li><strong>Western Union &amp; Money Gram <\/strong>dirigidos a Paulette Cowan, 52 Tuscan Way Ste 202-412, St Augustine, Florida 32092, EE. UU.<\/li>\n<\/ul>\n<div class=\"social-links\"><a title=\"Facebook\" href=\"https:\/\/www.facebook.com\/unitednationsforisrael\/\" target=\"blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/facebook.svg\" alt=\"Facebook\" \/><\/a><br \/>\n<a title=\"Twitter\" href=\"https:\/\/twitter.com\/DominiquaeBi\" target=\"blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/twitter.svg\" alt=\"Twitter\" \/><\/a><br \/>\n<a title=\"YouTube\" href=\"https:\/\/www.youtube.com\/@DominiquaeBiermanTV\" target=\"blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/youtube.svg\" alt=\"Youtube\" \/><\/a><br \/>\n<a title=\"Instagram\" href=\"https:\/\/www.instagram.com\/archbishopdominiquae\/\" target=\"blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/instagram.svg\" alt=\"Instagram\" \/><\/a><br \/>\n<a title=\"Zions Gospel\" href=\"https:\/\/www.zionsgospel.com\/\" target=\"blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/link.svg\" alt=\"Website\" \/><\/a><br \/>\n<a title=\"Email\" href=\"mailto:info@kad-esh.org\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/06\/envelope.svg\" alt=\"Email\" \/><\/a><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-57661\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant.jpg\" alt=\"Archbishop with a plant\" width=\"1200\" height=\"800\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-770x513.jpg 770w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-768x512.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-100x67.jpg 100w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-862x575.jpg 862w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-500x333.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2024\/10\/ab-with-plant-600x400.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h4><strong>\u00a1Traiga vida a Israel!<\/strong><\/h4>\n<p>Te invitamos a plantar un \u00e1rbol frutal en memoria de los israel\u00edes asesinados el 7 de octubre y en recuerdo de tus propios seres queridos que han partido.<br \/>\nDemos vida a los muertos plantando nuevos \u00e1rboles para sostener a Israel y recuperar la Tierra prometida.<\/p>\n<p><em>\u201cLos que siembran con l\u00e1grimas, segar\u00e1n con gritos de j\u00fabilo\u201d.<\/em> Salmo 126:5<\/p>\n<p><a class=\"button\" href=\"https:\/\/unitednationsforisrael.org\/es\/donations\/plantar-arboles\/\" target=\"_blank\" rel=\"noopener\"><strong>Plante \u00e1rboles en Israel<\/strong><\/a><\/p>\n<h4><strong>Apoye nuestros proyectos en Israel<\/strong><\/h4>\n<p>Ay\u00fadenos a seguir retransmitiendo desde Israel, ayudando a familias y comunidades israel\u00edes que necesitan urgentemente alimentos y suministros esenciales y plantando \u00e1rboles en Tierra Santa.<\/p>\n<p>Somos Tus Tropas en Tierra Santa.<\/p>\n<p><a class=\"button\" href=\"https:\/\/unitednationsforisrael.org\/es\/donaciones\/proyectos-en-israel\/\" target=\"_blank\" rel=\"noopener\"><strong>Apoye a Israel <\/strong>\u2192<\/a><\/p>\n<h5><strong>Suscr\u00edbase a nuestro canal de YouTube<\/strong><\/h5>\n<p>Vea las \u00faltimas transmisiones de la Dra. Dominiquae Bierman<\/p>\n<p><a class=\"button\" href=\"https:\/\/www.youtube.com\/@despiertasefaradtv9541\" target=\"_blank\" rel=\"noopener\">Nuestro canal de YouTube \u2192<\/a><\/p>\n<h5><strong>Para ver las \u00faltimas noticias desde Israel, agr\u00e9guese a nuestro canal de Telegram<\/strong><\/h5>\n<p><a class=\"button\" href=\"https:\/\/t.me\/apostoldominiquae\"><strong>Telegram <\/strong>\u2192<\/a><\/p>\n<h5><strong>Ore y declara la Palabra sobre Israel<\/strong><\/h5>\n<p><a class=\"button\" href=\"https:\/\/kad-esh.org\/es\/oraciones-por-israel\/\"><strong>Oraciones por Israel \u2192<\/strong><\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-40065\" style=\"margin-top: 2em; margin-bottom: 0;\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner.jpg\" alt=\"UNIFY Banner\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-300x81.jpg 300w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-1024x277.jpg 1024w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-768x208.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-500x135.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-100x27.jpg 100w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-862x233.jpg 862w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-600x163.jpg 600w, https:\/\/kad-esh.org\/wp-content\/uploads\/2022\/08\/unify-banner-64x17.jpg 64w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h5><strong>Forme parte de las Naciones Unidas Por Israel \u2013 \u00a1Para una ocasi\u00f3n como esta!<\/strong><\/h5>\n<p><a class=\"button\" href=\"https:\/\/unitednationsforisrael.org\/es\/membresia\/\" target=\"_blank\" rel=\"noopener\"><strong>S\u00famese a UNIFY <\/strong>\u2192<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47748\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner.jpg\" alt=\"GRM Bible Institute banner\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner.jpg 1920w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-300x88.jpg 300w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-1024x299.jpg 1024w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-768x224.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-1536x448.jpg 1536w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-500x146.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-100x29.jpg 100w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-862x251.jpg 862w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-1200x350.jpg 1200w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-600x175.jpg 600w, https:\/\/kad-esh.org\/wp-content\/uploads\/2023\/07\/grm-bible-institute-banner-64x19.jpg 64w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h4><strong>\u00a1Estudie en el Instituto B\u00edblico Israel\u00ed AGIMAP!<\/strong><\/h4>\n<p>Nunca m\u00e1s necesitar\u00e1 volver a una escuela b\u00edblica. El Instituto B\u00edblico AGIMAP es una lavadora que le lleva a la verdad del siglo I. Descubrir\u00e1 el Evangelio original hecho en Si\u00f3n que ha hecho libres a muchos.<\/p>\n<p><strong>Testimonios de nuestros estudiantes:<\/strong><\/p>\n<p><em>Yo era el segundo al mando de una banda delictiva a nivel nacional, pero con la ayuda de YHVH y la Escuela B\u00edblica AGIMAP, he empezado a denunciarlo despu\u00e9s de 21 a\u00f1os de ser miembro. El enemigo me ha estado atacando por ello. Sabe que est\u00e1 perdiendo a un guerrero, pero ahora lucho en una guerra diferente para un Maestro diferente.<\/em> &#8211; J.M.<\/p>\n<p><em>Sol\u00eda estar confundido e inc\u00f3modo porque no sab\u00eda qu\u00e9 creer. Hay tantas doctrinas diferentes, todas en contra de las dem\u00e1s y ense\u00f1ando cosas diferentes. Ahora entiendo mejor el Evangelio y conozco las ra\u00edces de mi fe.<\/em> &#8211; E.P<\/p>\n<p><em>\u00a1He estado equivocado toda mi vida, pero ahora entiendo lo que Dios quiere de m\u00ed!<\/em> &#8211; R.D.<\/p>\n<p><a class=\"button\" href=\"https:\/\/www.grmbibleinstitute.com\/es\/\" target=\"_blank\" rel=\"noopener\">Inscr\u00edbase y empiece sus estudios \u2192<\/a><\/p>\n<p><em>*Se pueden solicitar becas totales o parciales en caso de extrema necesidad. Por favor, env\u00ede sus solicitudes a info@grmbibleschool.com explicando el motivo de su solicitud.<\/em><\/p>\n<h5><strong>Firma nuestra petici\u00f3n para prohibir la exhibici\u00f3n p\u00fablica de esv\u00e1sticas, banderas nazis y de Ham\u00e1s<\/strong><\/h5>\n<p><a class=\"button\" href=\"https:\/\/www.change.org\/BanNeoNazism-Evil-Can-Be-Stopped\" target=\"_blank\" rel=\"noopener\">Firmar ahora \u2192<\/a><\/p>\n<h4><strong>Apoye el Ministerio de Prisiones MAP<\/strong><\/h4>\n<p>El ministerio de Prisiones MAP, iniciado por el Rabino Baruch Bierman, se ha expandido r\u00e1pidamente. Estamos llegando a tener miles de alumnos estudiando la Escuela B\u00edblica AGIMAP tras las rejas. \u00a1Muchas vidas est\u00e1n siendo completamente transformadas!<\/p>\n<p>Me he equivocado toda mi vida, \u00a1pero ahora entiendo lo que Dios quiere de m\u00ed por primera vez en mi vida!<\/p>\n<p><strong> &#8211; Ronald<\/strong><\/p>\n<p>\u00a1La Escuela B\u00edblica AGIMAP ha salvado mi vida! No estaba bien f\u00edsicamente, y mi vida espiritual pend\u00eda de un hilo porque todo estaba construido sobre falsas doctrinas y mentiras. Ahora tengo una relaci\u00f3n profunda, sana y floreciente con Yeshua.<\/p>\n<p><strong> &#8211; Deborah<\/strong><\/p>\n<p>Necesito desesperadamente que Dios entre en mi vida y me salve de esta forma de vivir tan desastrosa. Gracias por este libro. Oren por m\u00ed, por favor, y espero que contin\u00faen ense\u00f1\u00e1ndome; \u00a1lo necesito!<\/p>\n<p><strong>&#8211; Jerred<\/strong><\/p>\n<p>Las verdades que he aprendido a trav\u00e9s de la Escuela B\u00edblica AGIMAP me han cambiado para ser un mejor ciudadano en Su Reino.<\/p>\n<p><strong> &#8211; Scott<\/strong><\/p>\n<p><strong>Apoye este ministerio que cambia vidas mediante oraciones y donativos.<\/strong><\/p>\n<p><a class=\"button\" href=\"https:\/\/kad-esh.org\/es\/ministerio-de-prisiones\/\"><strong>Ministerio de Prisiones MAP \u2192<\/strong><\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-73014\" src=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire.jpg\" alt=\"Vasijas de Fuego\" width=\"300\" height=\"auto\" srcset=\"https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire.jpg 1000w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-490x770.jpg 490w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-764x1200.jpg 764w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-768x1206.jpg 768w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-500x785.jpg 500w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-600x942.jpg 600w, https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/01\/SPA-vessels-of-fire-862x1353.jpg 862w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Lee los incre\u00edbles testimonios de nuestros estudiantes reclusos de<br \/>\n<strong>Vasijas de Fuego &#8211; Testimonios desde detr\u00e1s de las rejas.<\/strong><\/p>\n<p><a class=\"button\" href=\"https:\/\/www.zionsgospel.com\/es\/tienda\/vasijas-de-fuego\/\" target=\"_blank\" rel=\"noopener\"><strong>Ordenar el Libro \u2192<\/strong><\/a><\/p>\n<h4><strong>Nuestros Ministerios y Recursos<\/strong><\/h4>\n<p><a class=\"button\" href=\"https:\/\/linktr.ee\/apostol_dominiquae\" target=\"_blank\" rel=\"noopener\">Vis\u00edtenos \u2192<\/a><\/p>\n<p><strong>Para invitar a los ap\u00f3stoles jud\u00edos a predicar y ministrar en su ciudad y pa\u00eds, <\/strong>env\u00edenos un correo electr\u00f3nico a <a href=\"mailto:info@kad-esh.org\">info@kad-esh.org.<\/a><\/p>\n<h4><strong>\u00a1Sea uno de los 70 Justos de las Naciones!<\/strong><\/h4>\n<p>Convi\u00e9rtete en un socio especial de las Naciones Unidas para Israel comprometi\u00e9ndose a hacer una ofrenda de amor mensual de 100 d\u00f3lares o m\u00e1s. Como miembro de \u00abJustos de las Naciones\u00bb, tendr\u00e1 acceso a reuniones exclusivas en l\u00ednea con la Dra. Dominiquae Bierman.<\/p>\n<p><a class=\"button\" href=\"https:\/\/unitednationsforisrael.org\/es\/donaciones\/unase-a-los-justos-de-las-naciones\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00danase a los Justos de las Naciones \u2192<\/strong><\/a><\/p>\n<\/div><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Porci\u00f3n de la Fiesta de SHAVUOT \u2013 Shemot (\u00c9xodo) 19:1-20:23. Haftar\u00e1: 1:1-28 Al ver el pueblo que Mois\u00e9s tardaba en bajar del monte, fueron a ver a Aar\u00f3n y le dijeron: \u00abAnda, haznos unos dioses que vayan delante de nosotros, &#8230; <\/p>\n<div><a href=\"https:\/\/kad-esh.org\/es\/shabbat-letter-ads\/\" class=\"more-link\">Lee mas<\/a><\/div>\n","protected":false},"author":14,"featured_media":78638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[107],"tags":[],"class_list":["post-78524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carta-de-shabbat"],"taxonomy_info":{"category":[{"value":107,"label":"Carta de Shabbat"}]},"featured_image_src_large":["https:\/\/kad-esh.org\/wp-content\/uploads\/2026\/05\/are-you-waiting-1-1200x849.jpg",742,525,true],"author_info":{"display_name":"WB","author_link":"https:\/\/kad-esh.org\/es\/author\/wb\/"},"comment_info":0,"category_info":[{"term_id":107,"name":"Carta de Shabbat","slug":"carta-de-shabbat","term_group":0,"term_taxonomy_id":107,"taxonomy":"category","description":"","parent":0,"count":83,"filter":"raw","cat_ID":107,"category_count":83,"category_description":"","cat_name":"Carta de Shabbat","category_nicename":"carta-de-shabbat","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/posts\/78524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/comments?post=78524"}],"version-history":[{"count":2,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/posts\/78524\/revisions"}],"predecessor-version":[{"id":78527,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/posts\/78524\/revisions\/78527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/media\/78638"}],"wp:attachment":[{"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/media?parent=78524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/categories?post=78524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kad-esh.org\/es\/wp-json\/wp\/v2\/tags?post=78524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}